{"id":3586,"date":"2020-12-20T22:54:38","date_gmt":"2020-12-20T21:54:38","guid":{"rendered":"https:\/\/sucurriculum.com\/noticias\/?p=3586"},"modified":"2020-12-20T22:54:38","modified_gmt":"2020-12-20T21:54:38","slug":"enfrentamiento-en-el-gobierno-por-la-subida-del-salario-minimo","status":"publish","type":"post","link":"https:\/\/sucurriculum.com\/noticias\/enfrentamiento-en-el-gobierno-por-la-subida-del-salario-minimo\/","title":{"rendered":"Enfrentamiento en el Gobierno por la subida del salario m\u00ednimo"},"content":{"rendered":"\n<p>Las discrepancias en el seno del Gobierno de coalici\u00f3n son ya p\u00fablicas y notorias. Ya ni siquiera lo ocultan de cara a la galer\u00eda, tras lo visto esta semana entre el intercambio de palabras entre Pablo Iglesias y Mar\u00eda Jes\u00fas Montero en uno de los pasillos del Congreso. Pero no ha sido el \u00fanico. Nadia Calvi\u00f1o, Jos\u00e9 Luis Escriv\u00e1, Pablo Iglesias y Yolanda D\u00edaz han intercambiado pareceres divergentes en los medios de comunicaci\u00f3n durante toda la semana. La \u00faltima en hacerlo ha sido la ministra de Trabajo y Econom\u00eda Social, Yolanda D\u00edaz, que ha reconocido ya sin tapujos que existen serias discrepancias en el seno del Gobierno en torno a uno de los temas estrella en el sprint final del a\u00f1o: la subida del salario m\u00ednimo interprofesional (SMI) para 2021.<\/p>\n\n\n\n<p>\u201cComo en todas las materias, hay distintas opiniones y eso es bueno, no se trata de que seamos un\u00edvocos. Luego el Gobierno decidir\u00e1 y lo haremos colectivamente\u201d, ha subrayado D\u00edaz en declaraciones a La Sexta. La ministra ha adelantado que cuenta con el benepl\u00e1cito del presidente del Gobierno, Pedro S\u00e1nchez, \u201cque entiende la utilidad del SMI para combatir la pobreza y la desigualdad\u201d. D\u00edaz cree que aunque \u201cuna parte de la econom\u00eda\u201d siempre est\u00e1 por congelarlo o incluso rebajarlo, subirlo en la medida en que lo hizo el Gobierno socialista \u201cno fue una cat\u00e1strofe\u201d, sino bueno para la econom\u00eda y para luchar contra la desigualdad. \u201cLas distintas voces que sobre este asunto se han escuchado en el seno del Gobierno han abierto un debate bueno y normal en un Gobierno de coalici\u00f3n\u201d, y ha defendido que esto \u201cno va por partidos pol\u00edticos\u201d y que la decisi\u00f3n final se tomar\u00e1 de forma consensuada en el Consejo de Ministros.<\/p>\n\n\n\n<p>La titular de Trabajo tambi\u00e9n ha criticado la postura de la CEOE, que se opone al alza del salario m\u00ednimo haciendo uso de un \u201celemento discursivo, ideol\u00f3gico\u201d, ya que se trata de un argumento que ya esgrimi\u00f3 hace un a\u00f1o, cuando \u201cEspa\u00f1a crec\u00eda\u201d. La ministra ha asegurado que el discurso \u201csiempre es el mismo. Exista crisis o no, hay una parte de la econom\u00eda que siempre habla de congelar o bajar el SMI\u201d, pero que es necesario elevar el salario de los que menos ganan. D\u00edaz ha explicado que mientras los salarios bajo convenio se van a incrementar entre un 1,5% y un 1,8%, \u201cno tiene sentido dejar fuera a los que m\u00e1s lo necesitan\u201d y se ha mostrado convencida de que el l\u00edder de la patronal, Antonio Garamendi, \u201cno comparte que haya trabajadores pobres y los tenemos por encima del 13%\u201d, ha apuntado.<\/p>\n\n\n\n<p>La ministra ha reconocido que hay empresas que lo est\u00e1n pasando mal, pero acto seguido ha recordado que el Gobierno ha puesto en marcha medidas para salvar a medio mill\u00f3n de empresas, que se est\u00e1n beneficiando de exoneraciones de cuotas que incluso llegan al 100%, mientras los salarios asociados a los ERTE suponen el 70% del que se percib\u00eda. D\u00edaz, que ha vuelto a pedir a la CEOE \u201cempat\u00eda con su pueblo\u201d para que acepte la subida del SMI, tambi\u00e9n ha considerado \u201cfalaz\u201d el discurso de la patronal para oponerse a esta medida, pues no se est\u00e1 hablando de subir el SMI a los trabajadores con convenio colectivo, como los de la hosteler\u00eda, sino precisamente a quienes no lo tienen.<\/p>\n\n\n\n<p>D\u00edaz ha aprovechado adem\u00e1s para exponer de nuevo los argumentos que justificar\u00edan una subida del SMI el a\u00f1o pr\u00f3ximo: suben las pensiones y los sueldos de los funcionarios (0,9%), el salario medio pactado en convenio (una media de entre el 1,5% y el 1,8%) y el SMI en todos los pa\u00edses que lo tienen, y todo ello pese a la pandemia. Por ello, ha reiterado que \u201cno tendr\u00eda sentido\u201d y no ser\u00eda coherente dejar fuera de estas subidas precisamente a los trabajadores m\u00e1s d\u00e9biles, los que cobran el SMI, que adem\u00e1s ver\u00edan recortado su poder adquisitivo si esta renta no se actualiza, pues la inflaci\u00f3n prevista para 2021 es del 0,9%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las discrepancias en el seno del Gobierno de coalici\u00f3n son ya p\u00fablicas y notorias. Ya ni siquiera lo ocultan de cara a la galer\u00eda.<\/p>\n","protected":false},"author":2,"featured_media":3587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[2125,36,245,972,1499],"class_list":["post-3586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-actualidad","tag-enfrentamiento","tag-gobierno","tag-minimo","tag-salario","tag-subida"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sucurriculum.com\/noticias\/wp-json\/wp\/v2\/posts\/3586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sucurriculum.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sucurriculum.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sucurriculum.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sucurriculum.com\/noticias\/wp-json\/wp\/v2\/comments?post=3586"}],"version-history":[{"count":1,"href":"https:\/\/sucurriculum.com\/noticias\/wp-json\/wp\/v2\/posts\/3586\/revisions"}],"predecessor-version":[{"id":3588,"href":"https:\/\/sucurriculum.com\/noticias\/wp-json\/wp\/v2\/posts\/3586\/revisions\/3588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sucurriculum.com\/noticias\/wp-json\/wp\/v2\/media\/3587"}],"wp:attachment":[{"href":"https:\/\/sucurriculum.com\/noticias\/wp-json\/wp\/v2\/media?parent=3586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sucurriculum.com\/noticias\/wp-json\/wp\/v2\/categories?post=3586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sucurriculum.com\/noticias\/wp-json\/wp\/v2\/tags?post=3586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}